

{"id":2515,"date":"2010-07-17T00:00:00","date_gmt":"2010-07-17T00:00:00","guid":{"rendered":"https:\/\/guadalminagolf.com\/sin-categorizar\/laura-gomez-campeona-de-andalucia\/"},"modified":"2010-07-17T00:00:00","modified_gmt":"2010-07-17T00:00:00","slug":"laura-gomez-campeona-de-andalucia","status":"publish","type":"post","link":"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/","title":{"rendered":"Laura Gomez, Campeona de Andalucia"},"content":{"rendered":"<p>Nuestra socia <strong>Laura Gomez<\/strong> ha ganado el <strong>Campeonato Internacional de Andaluc&iacute;a Infantil<\/strong> celebrado en Atalaya. <strong>Andr&eacute;s Tamayo y Phil Barrena <\/strong>acabaron en segunda posici&oacute;n de sus categor&iacute;as.<\/p>\n<p>Felicidades<\/p>\n<p>LOGO GUADALMINA.JPG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra socia <strong>Laura Gomez<\/strong> ha ganado el <strong>Campeonato Internacional de Andaluc&iacute;a Infantil<\/strong> celebrado en Atalaya. <strong>Andr&eacute;s Tamayo y Phil Barrena <\/strong>acabaron en segunda posici&oacute;n de sus categor&iacute;as.<\/p>\n<p>Felicidades<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[91],"tags":[],"class_list":["post-2515","post","type-post","status-publish","format-standard","hentry","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Laura Gomez, Campeona de Andalucia - Real Club de Golf Guadalmina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laura Gomez, Campeona de Andalucia - Real Club de Golf Guadalmina\" \/>\n<meta property=\"og:description\" content=\"Nuestra socia Laura Gomez ha ganado el Campeonato Internacional de Andaluc&iacute;a Infantil celebrado en Atalaya. Andr&eacute;s Tamayo y Phil Barrena acabaron en segunda posici&oacute;n de sus categor&iacute;as.Felicidades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/\" \/>\n<meta property=\"og:site_name\" content=\"Real Club de Golf Guadalmina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/Amigos.de.Guadalmina\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-17T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.guadalminagolf.com\/wp-content\/uploads\/2023\/08\/logo-sin-fechas-2-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1526\" \/>\n\t<meta property=\"og:image:height\" content=\"1809\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GuADalMnA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GuADalMnA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/es\\\/ultimas-noticias\\\/laura-gomez-campeona-de-andalucia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/es\\\/ultimas-noticias\\\/laura-gomez-campeona-de-andalucia\\\/\"},\"author\":{\"name\":\"GuADalMnA\",\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/#\\\/schema\\\/person\\\/9a4e4fa1970b0c1b47cd752646e59419\"},\"headline\":\"Laura Gomez, Campeona de Andalucia\",\"datePublished\":\"2010-07-17T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/es\\\/ultimas-noticias\\\/laura-gomez-campeona-de-andalucia\\\/\"},\"wordCount\":44,\"publisher\":{\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/#organization\"},\"articleSection\":[\"\u00daltimas Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/es\\\/ultimas-noticias\\\/laura-gomez-campeona-de-andalucia\\\/\",\"url\":\"https:\\\/\\\/www.guadalminagolf.com\\\/es\\\/ultimas-noticias\\\/laura-gomez-campeona-de-andalucia\\\/\",\"name\":\"Laura Gomez, Campeona de Andalucia - Real Club de Golf Guadalmina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/#website\"},\"datePublished\":\"2010-07-17T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/es\\\/ultimas-noticias\\\/laura-gomez-campeona-de-andalucia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.guadalminagolf.com\\\/es\\\/ultimas-noticias\\\/laura-gomez-campeona-de-andalucia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/es\\\/ultimas-noticias\\\/laura-gomez-campeona-de-andalucia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.guadalminagolf.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laura Gomez, Campeona de Andalucia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/#website\",\"url\":\"https:\\\/\\\/www.guadalminagolf.com\\\/\",\"name\":\"Real Club de Golf Guadalmina\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/#organization\"},\"alternateName\":\"RCG Guadalmina\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.guadalminagolf.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/#organization\",\"name\":\"Real Club de Golf Guadalmina\",\"alternateName\":\"Real Club de Golf Guadalmina\",\"url\":\"https:\\\/\\\/www.guadalminagolf.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.guadalminagolf.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-sin-fechas-2-14.jpg\",\"contentUrl\":\"https:\\\/\\\/www.guadalminagolf.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-sin-fechas-2-14.jpg\",\"width\":1526,\"height\":1809,\"caption\":\"Real Club de Golf Guadalmina\"},\"image\":{\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/Amigos.de.Guadalmina\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.guadalminagolf.com\\\/#\\\/schema\\\/person\\\/9a4e4fa1970b0c1b47cd752646e59419\",\"name\":\"GuADalMnA\",\"sameAs\":[\"http:\\\/\\\/guadalmina.golfenred.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laura Gomez, Campeona de Andalucia - Real Club de Golf Guadalmina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/","og_locale":"es_ES","og_type":"article","og_title":"Laura Gomez, Campeona de Andalucia - Real Club de Golf Guadalmina","og_description":"Nuestra socia Laura Gomez ha ganado el Campeonato Internacional de Andaluc&iacute;a Infantil celebrado en Atalaya. Andr&eacute;s Tamayo y Phil Barrena acabaron en segunda posici&oacute;n de sus categor&iacute;as.Felicidades","og_url":"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/","og_site_name":"Real Club de Golf Guadalmina","article_publisher":"https:\/\/www.facebook.com\/groups\/Amigos.de.Guadalmina","article_published_time":"2010-07-17T00:00:00+00:00","og_image":[{"width":1526,"height":1809,"url":"https:\/\/www.guadalminagolf.com\/wp-content\/uploads\/2023\/08\/logo-sin-fechas-2-12.jpg","type":"image\/jpeg"}],"author":"GuADalMnA","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"GuADalMnA"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/#article","isPartOf":{"@id":"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/"},"author":{"name":"GuADalMnA","@id":"https:\/\/www.guadalminagolf.com\/#\/schema\/person\/9a4e4fa1970b0c1b47cd752646e59419"},"headline":"Laura Gomez, Campeona de Andalucia","datePublished":"2010-07-17T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/"},"wordCount":44,"publisher":{"@id":"https:\/\/www.guadalminagolf.com\/#organization"},"articleSection":["\u00daltimas Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/","url":"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/","name":"Laura Gomez, Campeona de Andalucia - Real Club de Golf Guadalmina","isPartOf":{"@id":"https:\/\/www.guadalminagolf.com\/#website"},"datePublished":"2010-07-17T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.guadalminagolf.com\/es\/ultimas-noticias\/laura-gomez-campeona-de-andalucia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.guadalminagolf.com\/es\/"},{"@type":"ListItem","position":2,"name":"Laura Gomez, Campeona de Andalucia"}]},{"@type":"WebSite","@id":"https:\/\/www.guadalminagolf.com\/#website","url":"https:\/\/www.guadalminagolf.com\/","name":"Real Club de Golf Guadalmina","description":"","publisher":{"@id":"https:\/\/www.guadalminagolf.com\/#organization"},"alternateName":"RCG Guadalmina","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.guadalminagolf.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.guadalminagolf.com\/#organization","name":"Real Club de Golf Guadalmina","alternateName":"Real Club de Golf Guadalmina","url":"https:\/\/www.guadalminagolf.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.guadalminagolf.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.guadalminagolf.com\/wp-content\/uploads\/2023\/08\/logo-sin-fechas-2-14.jpg","contentUrl":"https:\/\/www.guadalminagolf.com\/wp-content\/uploads\/2023\/08\/logo-sin-fechas-2-14.jpg","width":1526,"height":1809,"caption":"Real Club de Golf Guadalmina"},"image":{"@id":"https:\/\/www.guadalminagolf.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/Amigos.de.Guadalmina"]},{"@type":"Person","@id":"https:\/\/www.guadalminagolf.com\/#\/schema\/person\/9a4e4fa1970b0c1b47cd752646e59419","name":"GuADalMnA","sameAs":["http:\/\/guadalmina.golfenred.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.guadalminagolf.com\/es\/wp-json\/wp\/v2\/posts\/2515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.guadalminagolf.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guadalminagolf.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guadalminagolf.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guadalminagolf.com\/es\/wp-json\/wp\/v2\/comments?post=2515"}],"version-history":[{"count":0,"href":"https:\/\/www.guadalminagolf.com\/es\/wp-json\/wp\/v2\/posts\/2515\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.guadalminagolf.com\/es\/wp-json\/wp\/v2\/media?parent=2515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guadalminagolf.com\/es\/wp-json\/wp\/v2\/categories?post=2515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guadalminagolf.com\/es\/wp-json\/wp\/v2\/tags?post=2515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}